{"id":2546,"date":"2025-07-23T17:05:31","date_gmt":"2025-07-23T15:05:31","guid":{"rendered":"https:\/\/mandaris.com\/?page_id=2546"},"modified":"2025-07-25T16:37:39","modified_gmt":"2025-07-25T14:37:39","slug":"rafael-sucre","status":"publish","type":"page","link":"https:\/\/mandaris.com\/de\/portrait\/unsere-mitarbeitenden\/rafael-sucre\/","title":{"rendered":"Rafael Sucre"},"content":{"rendered":"\n<p><strong>Trainee<\/strong><\/p>\n\n\n\n<p>Sprachen: Deutsch, Englisch, Spanisch<\/p>\n\n\n\n<p>Rafael Sucre absolviert eine vierj\u00e4hrige schulische Ausbildung an der Wirtschaftsmittelschule (WMS). Nach drei erfolgreich abgeschlossenen Schuljahren verbringt er sein letztes Ausbildungsjahr als Praktikant bei der Mandaris AG. W\u00e4hrend seines Praktikums am Standort Basel erh\u00e4lt er spannende Einblicke in verschiedene Abteilungen und Aufgabenbereiche.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trainee Sprachen: Deutsch, Englisch, Spanisch Rafael Sucre absolviert eine vierj\u00e4hrige schulische Ausbildung an der Wirtschaftsmittelschule (WMS). Nach drei erfolgreich abgeschlossenen Schuljahren verbringt er sein letztes Ausbildungsjahr als Praktikant bei der Mandaris AG. W\u00e4hrend seines Praktikums am Standort Basel erh\u00e4lt er spannende Einblicke in verschiedene Abteilungen und Aufgabenbereiche.<\/p>\n","protected":false},"author":6,"featured_media":150,"parent":1129,"menu_order":12,"comment_status":"closed","ping_status":"closed","template":"views\/page-employee.php","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-2546","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/pages\/2546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/comments?post=2546"}],"version-history":[{"count":7,"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/pages\/2546\/revisions"}],"predecessor-version":[{"id":2656,"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/pages\/2546\/revisions\/2656"}],"up":[{"embeddable":true,"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/pages\/1129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/media\/150"}],"wp:attachment":[{"href":"https:\/\/mandaris.com\/de\/wp-json\/wp\/v2\/media?parent=2546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}